{"id":20009,"date":"2025-10-15T17:06:01","date_gmt":"2025-10-15T15:06:01","guid":{"rendered":"https:\/\/www.museodelapaz.eus\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/"},"modified":"2025-11-21T12:00:34","modified_gmt":"2025-11-21T11:00:34","slug":"los-nazis-atacan-violentamente-a-la-prensa-inglesa","status":"publish","type":"documento","link":"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/","title":{"rendered":"Los &#8216;nazis&#8217; atacan violentamente a la Prensa inglesa"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"descriptor":[2453],"tipo-de-documento":[620],"class_list":["post-20009","documento","type-documento","status-publish","hentry","descriptor-guerra-civil-bombardeo-de-gernika-prensa-extranjera-nazis-ingleses","tipo-de-documento-hemeroteca-hem"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los &#039;nazis&#039; atacan violentamente a la Prensa inglesa - Museo de la Paz de Gernika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los &#039;nazis&#039; atacan violentamente a la Prensa inglesa - Museo de la Paz de Gernika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo de la Paz de Gernika\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T11:00:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/documento\\\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/documento\\\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\\\/\",\"name\":\"Los 'nazis' atacan violentamente a la Prensa inglesa - Museo de la Paz de Gernika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/#website\"},\"datePublished\":\"2025-10-15T15:06:01+00:00\",\"dateModified\":\"2025-11-21T11:00:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/documento\\\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/documento\\\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/documento\\\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los &#8216;nazis&#8217; atacan violentamente a la Prensa inglesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/\",\"name\":\"Museo de la Paz de Gernika\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/#organization\",\"name\":\"Museo de la Paz de Gernika\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"caption\":\"Museo de la Paz de Gernika\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los 'nazis' atacan violentamente a la Prensa inglesa - Museo de la Paz de Gernika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/","og_locale":"fr_FR","og_type":"article","og_title":"Los 'nazis' atacan violentamente a la Prensa inglesa - Museo de la Paz de Gernika","og_url":"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/","og_site_name":"Museo de la Paz de Gernika","article_modified_time":"2025-11-21T11:00:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/","url":"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/","name":"Los 'nazis' atacan violentamente a la Prensa inglesa - Museo de la Paz de Gernika","isPartOf":{"@id":"https:\/\/www.museodelapaz.eus\/fr\/#website"},"datePublished":"2025-10-15T15:06:01+00:00","dateModified":"2025-11-21T11:00:34+00:00","breadcrumb":{"@id":"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.museodelapaz.eus\/fr\/documento\/los-nazis-atacan-violentamente-a-la-prensa-inglesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.museodelapaz.eus\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Los &#8216;nazis&#8217; atacan violentamente a la Prensa inglesa"}]},{"@type":"WebSite","@id":"https:\/\/www.museodelapaz.eus\/fr\/#website","url":"https:\/\/www.museodelapaz.eus\/fr\/","name":"Museo de la Paz de Gernika","description":"","publisher":{"@id":"https:\/\/www.museodelapaz.eus\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museodelapaz.eus\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.museodelapaz.eus\/fr\/#organization","name":"Museo de la Paz de Gernika","url":"https:\/\/www.museodelapaz.eus\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.museodelapaz.eus\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","contentUrl":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","caption":"Museo de la Paz de Gernika"},"image":{"@id":"https:\/\/www.museodelapaz.eus\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.museodelapaz.eus\/fr\/wp-json\/wp\/v2\/documento\/20009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museodelapaz.eus\/fr\/wp-json\/wp\/v2\/documento"}],"about":[{"href":"https:\/\/www.museodelapaz.eus\/fr\/wp-json\/wp\/v2\/types\/documento"}],"wp:attachment":[{"href":"https:\/\/www.museodelapaz.eus\/fr\/wp-json\/wp\/v2\/media?parent=20009"}],"wp:term":[{"taxonomy":"descriptor","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/fr\/wp-json\/wp\/v2\/descriptor?post=20009"},{"taxonomy":"tipo-de-documento","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/fr\/wp-json\/wp\/v2\/tipo-de-documento?post=20009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}