{"id":19268,"date":"2025-10-15T17:04:46","date_gmt":"2025-10-15T15:04:46","guid":{"rendered":"https:\/\/www.museodelapaz.eus\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/"},"modified":"2025-11-21T11:59:01","modified_gmt":"2025-11-21T10:59:01","slug":"el-gobierno-vasco-y-las-evacuaciones-de-los-ninos","status":"publish","type":"documento","link":"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/","title":{"rendered":"El Gobierno Vasco y las evacuaciones de los ni\u00f1os"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"descriptor":[2033],"tipo-de-documento":[266],"class_list":["post-19268","documento","type-documento","status-publish","hentry","descriptor-guerra-civil-evacuacion-ninos","tipo-de-documento-monografia-mon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno Vasco y las evacuaciones de los ni\u00f1os - Museo de la Paz de Gernika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno Vasco y las evacuaciones de los ni\u00f1os - Museo de la Paz de Gernika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo de la Paz de Gernika\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T10:59:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\\\/\",\"name\":\"El Gobierno Vasco y las evacuaciones de los ni\u00f1os - Museo de la Paz de Gernika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#website\"},\"datePublished\":\"2025-10-15T15:04:46+00:00\",\"dateModified\":\"2025-11-21T10:59:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno Vasco y las evacuaciones de los ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/\",\"name\":\"Museo de la Paz de Gernika\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#organization\",\"name\":\"Museo de la Paz de Gernika\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"caption\":\"Museo de la Paz de Gernika\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno Vasco y las evacuaciones de los ni\u00f1os - Museo de la Paz de Gernika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/","og_locale":"en_US","og_type":"article","og_title":"El Gobierno Vasco y las evacuaciones de los ni\u00f1os - Museo de la Paz de Gernika","og_url":"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/","og_site_name":"Museo de la Paz de Gernika","article_modified_time":"2025-11-21T10:59:01+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/","url":"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/","name":"El Gobierno Vasco y las evacuaciones de los ni\u00f1os - Museo de la Paz de Gernika","isPartOf":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#website"},"datePublished":"2025-10-15T15:04:46+00:00","dateModified":"2025-11-21T10:59:01+00:00","breadcrumb":{"@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/el-gobierno-vasco-y-las-evacuaciones-de-los-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.museodelapaz.eus\/en\/home\/"},{"@type":"ListItem","position":2,"name":"El Gobierno Vasco y las evacuaciones de los ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/www.museodelapaz.eus\/en\/#website","url":"https:\/\/www.museodelapaz.eus\/en\/","name":"Museo de la Paz de Gernika","description":"","publisher":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museodelapaz.eus\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.museodelapaz.eus\/en\/#organization","name":"Museo de la Paz de Gernika","url":"https:\/\/www.museodelapaz.eus\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museodelapaz.eus\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","contentUrl":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","caption":"Museo de la Paz de Gernika"},"image":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/documento\/19268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/documento"}],"about":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/types\/documento"}],"wp:attachment":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/media?parent=19268"}],"wp:term":[{"taxonomy":"descriptor","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/descriptor?post=19268"},{"taxonomy":"tipo-de-documento","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/tipo-de-documento?post=19268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}