{"id":19266,"date":"2025-10-15T17:04:46","date_gmt":"2025-10-15T15:04:46","guid":{"rendered":"https:\/\/www.museodelapaz.eus\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/"},"modified":"2025-11-21T11:59:00","modified_gmt":"2025-11-21T10:59:00","slug":"coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris","status":"publish","type":"documento","link":"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/","title":{"rendered":"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l&#8217; Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"descriptor":[2031],"tipo-de-documento":[266],"class_list":["post-19266","documento","type-documento","status-publish","hentry","descriptor-guerra-civil-fuentes-archivos-bombardeo-de-gernika-frente-de-vizcaya-operaciones-militares","tipo-de-documento-monografia-mon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l&#039; Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris - Museo de la Paz de Gernika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l&#039; Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris - Museo de la Paz de Gernika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo de la Paz de Gernika\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T10:59:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\\\/\",\"name\":\"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l' Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris - Museo de la Paz de Gernika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#website\"},\"datePublished\":\"2025-10-15T15:04:46+00:00\",\"dateModified\":\"2025-11-21T10:59:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l&#8217; Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/\",\"name\":\"Museo de la Paz de Gernika\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#organization\",\"name\":\"Museo de la Paz de Gernika\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"caption\":\"Museo de la Paz de Gernika\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l' Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris - Museo de la Paz de Gernika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/","og_locale":"en_US","og_type":"article","og_title":"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l' Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris - Museo de la Paz de Gernika","og_url":"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/","og_site_name":"Museo de la Paz de Gernika","article_modified_time":"2025-11-21T10:59:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/","url":"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/","name":"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l' Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris - Museo de la Paz de Gernika","isPartOf":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#website"},"datePublished":"2025-10-15T15:04:46+00:00","dateModified":"2025-11-21T10:59:00+00:00","breadcrumb":{"@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/coleccion-documental-para-el-estudio-de-la-guerra-civil-en-euskadi-procedente-de-los-archivos-militares-franceses-1936-1937-archives-de-l-armee-de-terre-chateau-de-vicennes-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.museodelapaz.eus\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Colecci\u00f3n documental para el estudio de la Guerra Civil en Euskadi procedente de los archivos militares franceses (1936-1937): Archives de l&#8217; Arm\u00e9e de Terre, Ch\u00e2teau de Vicennes. Paris"}]},{"@type":"WebSite","@id":"https:\/\/www.museodelapaz.eus\/en\/#website","url":"https:\/\/www.museodelapaz.eus\/en\/","name":"Museo de la Paz de Gernika","description":"","publisher":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museodelapaz.eus\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.museodelapaz.eus\/en\/#organization","name":"Museo de la Paz de Gernika","url":"https:\/\/www.museodelapaz.eus\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museodelapaz.eus\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","contentUrl":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","caption":"Museo de la Paz de Gernika"},"image":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/documento\/19266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/documento"}],"about":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/types\/documento"}],"wp:attachment":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/media?parent=19266"}],"wp:term":[{"taxonomy":"descriptor","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/descriptor?post=19266"},{"taxonomy":"tipo-de-documento","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/tipo-de-documento?post=19266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}