{"id":19177,"date":"2025-10-15T17:04:36","date_gmt":"2025-10-15T15:04:36","guid":{"rendered":"https:\/\/www.museodelapaz.eus\/documento\/questions-diplomatiques\/"},"modified":"2025-11-21T11:58:49","modified_gmt":"2025-11-21T10:58:49","slug":"questions-diplomatiques","status":"publish","type":"documento","link":"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/","title":{"rendered":"Questions diplomatiques&#8230;"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"descriptor":[1650],"tipo-de-documento":[266],"class_list":["post-19177","documento","type-documento","status-publish","hentry","descriptor-guerra-civil-intervencion-extranjera","tipo-de-documento-monografia-mon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Questions diplomatiques... - Museo de la Paz de Gernika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Questions diplomatiques... - Museo de la Paz de Gernika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo de la Paz de Gernika\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T10:58:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/questions-diplomatiques\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/questions-diplomatiques\\\/\",\"name\":\"Questions diplomatiques... - Museo de la Paz de Gernika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#website\"},\"datePublished\":\"2025-10-15T15:04:36+00:00\",\"dateModified\":\"2025-11-21T10:58:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/questions-diplomatiques\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/questions-diplomatiques\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/documento\\\/questions-diplomatiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions diplomatiques&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/\",\"name\":\"Museo de la Paz de Gernika\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#organization\",\"name\":\"Museo de la Paz de Gernika\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.museodelapaz.eus\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-museo-de-la-paz-gernika-h-1.svg\",\"caption\":\"Museo de la Paz de Gernika\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museodelapaz.eus\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Questions diplomatiques... - Museo de la Paz de Gernika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/","og_locale":"en_US","og_type":"article","og_title":"Questions diplomatiques... - Museo de la Paz de Gernika","og_url":"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/","og_site_name":"Museo de la Paz de Gernika","article_modified_time":"2025-11-21T10:58:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/","url":"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/","name":"Questions diplomatiques... - Museo de la Paz de Gernika","isPartOf":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#website"},"datePublished":"2025-10-15T15:04:36+00:00","dateModified":"2025-11-21T10:58:49+00:00","breadcrumb":{"@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.museodelapaz.eus\/en\/documento\/questions-diplomatiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.museodelapaz.eus\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Questions diplomatiques&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.museodelapaz.eus\/en\/#website","url":"https:\/\/www.museodelapaz.eus\/en\/","name":"Museo de la Paz de Gernika","description":"","publisher":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museodelapaz.eus\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.museodelapaz.eus\/en\/#organization","name":"Museo de la Paz de Gernika","url":"https:\/\/www.museodelapaz.eus\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museodelapaz.eus\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","contentUrl":"https:\/\/www.museodelapaz.eus\/wp-content\/uploads\/2024\/05\/logo-museo-de-la-paz-gernika-h-1.svg","caption":"Museo de la Paz de Gernika"},"image":{"@id":"https:\/\/www.museodelapaz.eus\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/documento\/19177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/documento"}],"about":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/types\/documento"}],"wp:attachment":[{"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/media?parent=19177"}],"wp:term":[{"taxonomy":"descriptor","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/descriptor?post=19177"},{"taxonomy":"tipo-de-documento","embeddable":true,"href":"https:\/\/www.museodelapaz.eus\/en\/wp-json\/wp\/v2\/tipo-de-documento?post=19177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}